{"id":32444,"date":"2026-09-01T13:44:30","date_gmt":"2026-09-01T11:44:30","guid":{"rendered":"https:\/\/irisatelier.cz\/katalog-produktu\/unkategorisiert\/reeser\/"},"modified":"2026-09-01T13:44:30","modified_gmt":"2026-09-01T11:44:30","slug":"reeser","status":"publish","type":"product","link":"https:\/\/irisatelier.cz\/de\/katalog-produktu\/t-shirts-de\/reeser\/","title":{"rendered":"Reeser"},"content":{"rendered":"<ul>\n<li>Eingesetzte \u00c4rmel<\/li>\n<li>1&#215;1-Rippstrick am Halsausschnitt.<\/li>\n<li>Doppelnaht am Halsausschnitt, an den \u00c4rmelb\u00fcndchen und am unteren Saum.<\/li>\n<li>Innenliegendes Nackenband aus dem gleichen Material.<\/li>\n<\/ul>\n<h2>Zusammensetzung<\/h2>\n<p class=\"isSelectedEnd\">Material: Single Jersey, 50 % Bio-Baumwolle (Organic Open End Carded), 50 % recycelte Baumwolle (Recycled Open End Carded), st\u00fcckgewaschener Stoff.<\/p>\n<ul class=\"mb-6 flex w-full list-none flex-wrap justify-between gap-4 text-xs lg:text-sm\">\n<li><span class=\"font-bold\">Weight:<\/span> 220 GSM<\/li>\n<\/ul>\n<h2>Pflegehinweise<\/h2>\n<p>Mit \u00e4hnlichen Farben waschen, den Aufdruck nicht b\u00fcgeln, auf links waschen und b\u00fcgeln.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Unisex-T-Shirt mit h\u00f6herem Stoffgewicht aus recycelter Baumwolle.<\/strong><\/p>\n<p>Der Preis gilt ausschlie\u00dflich f\u00fcr das Textil. Produkte von Stanley\/Stella k\u00f6nnen Sie nur mit individuellem Branding erwerben.<\/p>\n<p>Dieser Preis gilt bei einer Abnahme von bis zu 30 St\u00fcck. Bei gr\u00f6\u00dferen Bestellmengen wird der Preis individuell per E-Mail unter info@irisatelier.cz vereinbart. <\/p>\n<p><strong>Produktpersonalisierung<\/strong><\/p>\n<p>Sie k\u00f6nnen Ihre T-Shirts mit Ihrem Logo, Text oder einer Grafik bedrucken oder besticken lassen.<\/p>\n<p>Stickerei ist langlebig und repr\u00e4sentativ \u2013 eine ideale Wahl f\u00fcr Corporate Merch, Uniformen oder Mitarbeitergeschenke.<\/p>\n<p><strong>So funktioniert es:<\/strong><\/p>\n<ol>\n<li>F\u00fcgen Sie das Produkt Ihrer Wunschliste hinzu und senden Sie uns die Liste per E-Mail.<\/li>\n<li>F\u00fcgen Sie Ihr Logo im PDF-Format oder als PNG mit transparentem Hintergrund bei.<\/li>\n<li>Innerhalb von 24 Stunden erhalten Sie ein Preisangebot.<\/li>\n<li>Nach Freigabe des Entwurfs beginnen wir mit der Produktion.<\/li>\n<\/ol>\n<p><strong>Wichtige Informationen:<\/strong><\/p>\n<p>\u2014 Mindestbestellmenge f\u00fcr die Personalisierung: 1 St\u00fcck<\/p>\n<p>\u2014 Produktionszeit: 7\u201314 Werktage nach Freigabe<\/p>\n<p>\u2014 Bei Bestellungen \u00fcber 30 St\u00fcck: Preis auf Anfrage<\/p>\n<p>Kontakt: <a href=\"mailto:info@irisatelier.cz\">info@irisatelier.cz<\/a><\/p>\n<p><strong>Gro\u00dfe Farbpalette \u2013 weitere Farben finden Sie in der Bildergalerie.<br \/>\n<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-32395\" src=\"https:\/\/irisatelier.cz\/wp-content\/uploads\/2026\/09\/Snimek-obrazovky-2026-09-01-133545.png\" alt=\"\" width=\"254\" height=\"59\" srcset=\"https:\/\/irisatelier.cz\/wp-content\/uploads\/2026\/09\/Snimek-obrazovky-2026-09-01-133545.png 254w, https:\/\/irisatelier.cz\/wp-content\/uploads\/2026\/09\/Snimek-obrazovky-2026-09-01-133545-150x35.png 150w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/><\/p>\n<p><!-- notionvc: a1a4f9fb-4818-4d2e-ac86-e10cd58d4684 --><\/p>\n","protected":false},"featured_media":32437,"template":"","meta":[],"product_brand":[],"product_cat":[479],"product_tag":[],"class_list":["post-32444","product","type-product","status-publish","has-post-thumbnail","product_cat-t-shirts-de","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product\/32444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product\/32444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/media\/32437"}],"wp:attachment":[{"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/media?parent=32444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product_brand?post=32444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product_cat?post=32444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/irisatelier.cz\/de\/wp-json\/wp\/v2\/product_tag?post=32444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}